{"id":3990,"date":"2025-05-14T15:54:00","date_gmt":"2025-05-14T12:54:00","guid":{"rendered":"https:\/\/genaisa.eu\/?p=3990"},"modified":"2025-12-16T15:55:26","modified_gmt":"2025-12-16T13:55:26","slug":"boletin-del-proyecto-genaisa-numero-1","status":"publish","type":"post","link":"https:\/\/genaisa.eu\/es\/genaisa-project-newsletter-issue-1\/","title":{"rendered":"Bolet\u00edn del Proyecto GenAISA \u2013 N\u00famero #1"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>\u00a1Bienvenido al primer bolet\u00edn de la Generative AI Skills Academy (GenAISA)!<\/strong><strong><br><\/strong>Nos entusiasma compartir actualizaciones clave, logros iniciales y conocimientos de nuestro trabajo para construir la infraestructura de habilidades que Europa necesita en la era de la IA generativa.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es GenAISA?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GenAISA \u2013 Academia de Habilidades de IA Generativa<\/strong> es una iniciativa cofinanciada por Erasmus+ destinada a abordar la necesidad urgente de <strong>desarrollo de habilidades<\/strong> en el dominio de r\u00e1pida evoluci\u00f3n de <strong>Inteligencia Artificial Generativa (GenAI)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto con un consorcio europeo diverso de <a href=\"https:\/\/genaisa.eu\/es\/companeros-de-equipo\/\"><strong>13 socios<\/strong><\/a> Desde la academia, la educaci\u00f3n vocacional, la industria y la innovaci\u00f3n digital, nuestro objetivo es:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dise\u00f1o <strong>dos planes de estudio personalizados<\/strong> (ES y FP) sobre IA generativa<\/li>\n\n\n\n<li>Proporcionar <strong>microcredenciales<\/strong> a trav\u00e9s de un abierto <strong>Plataforma MOOC<\/strong><\/li>\n\n\n\n<li>Desarrollar una <strong>Pasaporte de competencias digitales<\/strong> para apoyar las trayectorias profesionales<\/li>\n\n\n\n<li>Identificar futuros perfiles laborales como <strong>Ingeniero r\u00e1pido<\/strong> y <strong>Desarrollador de IA generativa<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfEn qu\u00e9 hemos estado trabajando?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el <strong>Reuni\u00f3n de lanzamiento en diciembre de 2024<\/strong>, El consorcio ha logrado avances sustanciales en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A <strong>an\u00e1lisis integral de la brecha de habilidades<\/strong> Se complet\u00f3 el mapeo de las necesidades actuales de educaci\u00f3n y fuerza laboral de GenAI.<\/li>\n\n\n\n<li>La base de nuestra <strong>Curr\u00edculos de educaci\u00f3n superior y EFP<\/strong> fue reclutado<\/li>\n\n\n\n<li>Planes iniciales para nuestra <strong>Plataforma MOOC<\/strong> y <strong>Entorno de aprendizaje virtual<\/strong> se discutieron<\/li>\n\n\n\n<li>Nuestro sitio web <a href=\"https:\/\/genaisa.eu\/es\/\">www.genaisa.eu<\/a> Est\u00e1 activo y creciendo como centro de conocimiento central<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Nuevos hallazgos: Encuesta sobre IA y educaci\u00f3n en IA generativa<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de nuestro trabajo inicial, realizamos una <strong>encuesta paneuropea<\/strong> entre <strong>educadores, formadores e instituciones<\/strong> en 16 pa\u00edses para comprender mejor el estado actual de la educaci\u00f3n GenAI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los conocimientos clave incluyen:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>86%<\/strong> de los encuestados (ES + EFP combinadas) ya ofrecen o planean ofrecer educaci\u00f3n en IA<\/li>\n\n\n\n<li>Solo <strong>49%<\/strong> (Combinaciones de educaci\u00f3n superior y formaci\u00f3n profesional) actualmente ofrecen cursos espec\u00edficos de IA generativa<\/li>\n\n\n\n<li>La mayor\u00eda de las ofertas de GenAI est\u00e1n limitadas a <strong>talleres y cursos en l\u00ednea<\/strong>, con pocos programas acad\u00e9micos completos<\/li>\n\n\n\n<li><strong>Ingenier\u00eda<\/strong> Sigue siendo la disciplina dominante, pero existe una creciente necesidad de <strong>Centrado en el negocio y el usuario<\/strong> dominios<\/li>\n\n\n\n<li>Ya existen ejemplos de formaci\u00f3n profesional implementada en inteligencia artificial y big data<\/li>\n\n\n\n<li>Las instituciones reportan barreras como <strong>financiaci\u00f3n limitada<\/strong>, <strong>acceso a herramientas<\/strong>, y <strong>desaf\u00edos del desarrollo curricular<\/strong><strong><br><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Paralelamente, nuestro an\u00e1lisis del mercado laboral de <strong>M\u00e1s de 15.000 publicaciones relacionadas con la IA en toda la UE<\/strong> destacado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alta demanda de <strong>Pit\u00f3n<\/strong>, <strong>Gesti\u00f3n de proyectos<\/strong>, <strong>Dise\u00f1o UX<\/strong>, y <strong>Habilidades de comunicaci\u00f3n<\/strong><\/li>\n\n\n\n<li><strong>Habilidades blandas<\/strong> se est\u00e1n volviendo tan esenciales como los t\u00e9cnicos<\/li>\n\n\n\n<li>Est\u00e1n surgiendo nuevos roles laborales en todo el mundo <strong>sectores no tradicionales<\/strong>, incluyendo dise\u00f1o, atenci\u00f3n m\u00e9dica y fabricaci\u00f3n.<br><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estos hallazgos est\u00e1n dando forma directamente a nuestro plan de estudios y al contenido de la capacitaci\u00f3n, lo que garantiza que GenAISA ofrezca <strong>valor en el mundo real<\/strong> Tanto para los estudiantes como para los empleadores.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQue sigue?<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prueba de la <strong>planes de estudio y Pasaporte de Competencias Digitales<\/strong> comenzar\u00e1 en el segundo semestre de 2025<\/li>\n\n\n\n<li>Nuestro <strong>Plataforma de formaci\u00f3n y MOOC<\/strong> Se lanzar\u00e1 para usuarios piloto a principios de 2026.<\/li>\n\n\n\n<li>Mantente atento a las pr\u00f3ximas novedades <strong>eventos, talleres de capacitaci\u00f3n y oportunidades de colaboraci\u00f3n<\/strong><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>\u00a1Bienvenidos al primer bolet\u00edn de la Academia de Habilidades en IA Generativa (GenAISA)! Nos complace compartir novedades clave, logros iniciales y perspectivas de nuestro trabajo para construir la infraestructura de habilidades que Europa necesita en la era de la IA Generativa. \u00bfQu\u00e9 es GenAISA? GenAISA \u2013 Academia de Habilidades en IA Generativa es una iniciativa cofinanciada por Erasmus+ que busca abordar\u2026<\/p>","protected":false},"author":2,"featured_media":3991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[31],"tags":[],"class_list":["post-3990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-project-newsletters"],"acf":[],"taxonomy_info":{"category":[{"value":31,"label":"Project Newsletters"}]},"featured_image_src_large":["https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/12\/GenAISA-Newsletter-1-724x1024.png",724,1024,true],"author_info":{"display_name":"Nikolay Tsolev (RCCI)","author_link":"https:\/\/genaisa.eu\/es\/author\/ntsolev\/"},"comment_info":1,"category_info":[{"term_id":31,"name":"Project Newsletters","slug":"project-newsletters","term_group":0,"term_taxonomy_id":31,"taxonomy":"category","description":"Periodic newsletters from the GenAISA project with highlights, results, upcoming events, and opportunities.","parent":0,"count":2,"filter":"raw","cat_ID":31,"category_count":2,"category_description":"Periodic newsletters from the GenAISA project with highlights, results, upcoming events, and opportunities.","cat_name":"Project Newsletters","category_nicename":"project-newsletters","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/posts\/3990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/comments?post=3990"}],"version-history":[{"count":0,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/posts\/3990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/media\/3991"}],"wp:attachment":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/media?parent=3990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/categories?post=3990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/tags?post=3990"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}