{"id":3253,"date":"2025-01-04T15:04:17","date_gmt":"2025-01-04T15:04:17","guid":{"rendered":"https:\/\/genaisa.eu\/?post_type=expert&#038;p=3253"},"modified":"2025-01-16T15:09:18","modified_gmt":"2025-01-16T13:09:18","slug":"ainara-garcia","status":"publish","type":"expert","link":"https:\/\/genaisa.eu\/es\/expert\/ainara-garcia\/","title":{"rendered":"Ainara Garc\u00eda"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ainara Garc\u00eda es licenciada en Ingenier\u00eda Inform\u00e1tica y M\u00e1ster en Desarrollo de Aplicaciones Emprendedoras. Con 20 a\u00f1os de experiencia profesional en Grupo Oesia, donde ejerci\u00f3 como coordinadora de equipos de Desarrollo de Aplicaciones, Ainara aporta un amplio conocimiento del sector a su labor docente. Durante los dos \u00faltimos a\u00f1os ha sido docente en Politeknika Txorierri, aportando sus conocimientos a iniciativas educativas innovadoras como GenAISA.<\/p>","protected":false},"featured_media":3612,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"expert-organization":[23],"class_list":["post-3253","expert","type-expert","status-publish","has-post-thumbnail","hentry","expert-organization-politeknika-txorierri-txorierri"],"acf":[],"taxonomy_info":{"expert-organization":[{"value":23,"label":"Politeknika Txorierri (TXORIERRI)"}]},"featured_image_src_large":["https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Ainara-Garcia.png",750,750,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/expert\/3253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/expert"}],"about":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/types\/expert"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/media\/3612"}],"wp:attachment":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/media?parent=3253"}],"wp:term":[{"taxonomy":"expert-organization","embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/expert-organization?post=3253"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}