{"id":3251,"date":"2025-01-04T15:02:41","date_gmt":"2025-01-04T15:02:41","guid":{"rendered":"https:\/\/genaisa.eu\/?post_type=expert&#038;p=3251"},"modified":"2025-01-04T15:02:41","modified_gmt":"2025-01-04T15:02:41","slug":"anabel-menica","status":"publish","type":"expert","link":"https:\/\/genaisa.eu\/es\/expert\/anabel-menica\/","title":{"rendered":"Anabel Menica"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Anabel Menica cuenta con 30 a\u00f1os de experiencia en formaci\u00f3n profesional y ha sido responsable de internacionalizaci\u00f3n en Politeknika Txorierri desde 1999. Con una amplia experiencia en gesti\u00f3n de proyectos, ha desarrollado y contribuido a numerosos proyectos de innovaci\u00f3n internacionales para personal y estudiantes. Su trabajo se centra en el desarrollo de competencias, la pedagog\u00eda innovadora, la calidad del profesorado, el esp\u00edritu emprendedor y la internacionalizaci\u00f3n en la formaci\u00f3n profesional, lo que la convierte en una colaboradora vital para los objetivos del proyecto GenAISA.<\/p>","protected":false},"featured_media":3184,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"expert-organization":[23],"class_list":["post-3251","expert","type-expert","status-publish","has-post-thumbnail","hentry","expert-organization-politeknika-txorierri-txorierri"],"acf":[],"taxonomy_info":{"expert-organization":[{"value":23,"label":"Politeknika Txorierri (TXORIERRI)"}]},"featured_image_src_large":["https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Anabel-Menica.png",750,750,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/expert\/3251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/expert"}],"about":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/types\/expert"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/media\/3184"}],"wp:attachment":[{"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/media?parent=3251"}],"wp:term":[{"taxonomy":"expert-organization","embeddable":true,"href":"https:\/\/genaisa.eu\/es\/wp-json\/wp\/v2\/expert-organization?post=3251"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}