{"id":3094,"date":"2025-01-03T14:52:05","date_gmt":"2025-01-03T14:52:05","guid":{"rendered":"https:\/\/genaisa.eu\/?page_id=3094"},"modified":"2025-12-12T17:42:00","modified_gmt":"2025-12-12T15:42:00","slug":"%cf%83%cf%85%ce%bd%ce%b5%cf%81%ce%b3%ce%ac%cf%84%ce%b5%cf%82-%cf%84%ce%b7%cf%82-%ce%bf%ce%bc%ce%ac%ce%b4%ce%b1%cf%82","status":"publish","type":"page","link":"https:\/\/genaisa.eu\/el\/team-partners\/","title":{"rendered":"\u039f\u03bc\u03ac\u03b4\u03b1 &amp; \u03a3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b5\u03c2"},"content":{"rendered":"<style>.kb-row-layout-id3094_33aa1b-83 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_33aa1b-83 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_33aa1b-83 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_33aa1b-83 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_33aa1b-83 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_33aa1b-83 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_33aa1b-83 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3094_55b96c-83 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-4xl, 8rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column3094_55b96c-83 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3094_55b96c-83 > .kt-inside-inner-col,.kadence-column3094_55b96c-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column3094_55b96c-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_55b96c-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_55b96c-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_55b96c-83 > .kt-inside-inner-col{background-color:var(--global-palette3, #1A202C);background-image:url('https:\/\/genaisa.eu\/wp-content\/uploads\/2024\/10\/lines.png');background-size:cover;background-position:51% 84%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column3094_55b96c-83 > .kt-inside-inner-col:before{opacity:0.74;background-image:radial-gradient(ellipse at center bottom,var(u002du002dglobal-palette2) 0%,var(u002du002dglobal-palette3) 52%);}.kadence-column3094_55b96c-83{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_55b96c-83 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_55b96c-83 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_55b96c-83 kb-section-has-overlay\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_f71530-b8, .wp-block-kadence-advancedheading.kt-adv-heading3094_f71530-b8[data-kb-block=\"kb-adv-heading3094_f71530-b8\"]{text-align:center;font-size:var(--global-kb-font-size-xxl, 4rem);font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading3094_f71530-b8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_f71530-b8[data-kb-block=\"kb-adv-heading3094_f71530-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_f71530-b8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_f71530-b8[data-kb-block=\"kb-adv-heading3094_f71530-b8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3094_f71530-b8 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3094_f71530-b8\">Team &amp; Partners<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3094_77a284-6f, .wp-block-kadence-advancedheading.kt-adv-heading3094_77a284-6f[data-kb-block=\"kb-adv-heading3094_77a284-6f\"]{max-width:700px;margin-right:auto;margin-left:auto;text-align:center;font-weight:300;font-style:normal;font-family:var( u002du002dglobal-body-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3094_77a284-6f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_77a284-6f[data-kb-block=\"kb-adv-heading3094_77a284-6f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_77a284-6f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_77a284-6f[data-kb-block=\"kb-adv-heading3094_77a284-6f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3094_77a284-6f wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3094_77a284-6f\">Meet the professionals and organizations driving the GenAISA vision, uniting expertise and innovation to advance training in generative AI.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3094_7d724b-72{margin-bottom:0px;}.kb-row-layout-id3094_7d724b-72 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_7d724b-72 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_7d724b-72 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_7d724b-72 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_7d724b-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_7d724b-72 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_7d724b-72 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3094_a8ff73-29 > .kt-inside-inner-col,.kadence-column3094_a8ff73-29 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_a8ff73-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_a8ff73-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_a8ff73-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_a8ff73-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_a8ff73-29{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_a8ff73-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_a8ff73-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_a8ff73-29\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3094_deeb9f-49 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_deeb9f-49 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_deeb9f-49 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:700px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_deeb9f-49 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_deeb9f-49 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_deeb9f-49 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_deeb9f-49 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3094_db9f8e-46 > .kt-inside-inner-col{display:flex;}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col,.kadence-column3094_db9f8e-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_db9f8e-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_db9f8e-46{text-align:center;}.kadence-column3094_db9f8e-46{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_db9f8e-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column3094_db9f8e-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_db9f8e-46\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_261545-31, .wp-block-kadence-advancedheading.kt-adv-heading3094_261545-31[data-kb-block=\"kb-adv-heading3094_261545-31\"]{max-width:650px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.3;font-weight:500;font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading3094_261545-31 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_261545-31[data-kb-block=\"kb-adv-heading3094_261545-31\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_261545-31 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_261545-31[data-kb-block=\"kb-adv-heading3094_261545-31\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3094_261545-31 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3094_261545-31\">Our Partners: A Network of Excellence<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_df5c45-67 > .kt-inside-inner-col{display:flex;}.kadence-column3094_df5c45-67 > .kt-inside-inner-col,.kadence-column3094_df5c45-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_df5c45-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_df5c45-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_df5c45-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3094_df5c45-67{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_df5c45-67{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_df5c45-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_df5c45-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_df5c45-67{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3094_df5c45-67{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_df5c45-67{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_df5c45-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column3094_df5c45-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3094_df5c45-67{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_df5c45-67{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_df5c45-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_df5c45-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_df5c45-67\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_ddcf80-13, .wp-block-kadence-advancedheading.kt-adv-heading3094_ddcf80-13[data-kb-block=\"kb-adv-heading3094_ddcf80-13\"]{max-width:650px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3094_ddcf80-13 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_ddcf80-13[data-kb-block=\"kb-adv-heading3094_ddcf80-13\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_ddcf80-13 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_ddcf80-13[data-kb-block=\"kb-adv-heading3094_ddcf80-13\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3094_ddcf80-13 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3094_ddcf80-13\">GenAISA is powered by a diverse consortium of partners, including leading universities, vocational training centers, and industry innovators from across Europe. Each partner brings unique expertise and dedication, ensuring the project\u2019s success in reshaping the educational landscape.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3094_c1b5d1-5a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_c1b5d1-5a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_c1b5d1-5a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_c1b5d1-5a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_c1b5d1-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_c1b5d1-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_c1b5d1-5a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3094_ecba3c-15 > .kt-inside-inner-col,.kadence-column3094_ecba3c-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_ecba3c-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_ecba3c-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_ecba3c-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_ecba3c-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_ecba3c-15{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_ecba3c-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_ecba3c-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_ecba3c-15\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><style>.kb-portfolio-loop3947_e27353-53 .kb-portfolio-grid-wrap{column-gap:60px;}.kb-portfolio-loop3947_e27353-53 .kb-portfolio-grid-wrap{row-gap:60px;}.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item{background-color:var(--global-palette8, #F7FAFC);border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-portfolio-loop3947_e27353-53 .kb-portfolio-overlay-color{background-color:rgba(23, 104, 234, 0);}.kb-portfolio-loop3947_e27353-53 .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-color{background-color:rgba(158, 207, 229, 0.9);}.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item .entry-title{color:var(--global-palette3, #1A202C);padding:5px 0px 10px 0px;margin:0px 0px 0px 0px;font-size:19px;line-height:1.25;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:600;}.kb-portfolio-loop3947_e27353-53 .kb-filter-item{border-width:0px 0px 2px 0px;padding:5px 8px 5px 8px;margin:0px 10px 0px 0px;}.kb-portfolio-loop3947_e27353-53{margin-bottom:60px;}@media all and (max-width: 1024px){.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 1024px){.kb-portfolio-loop3947_e27353-53 .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 1024px){.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-portfolio-loop3947_e27353-53 .kb-portfolio-grid-wrap{column-gap:20px;row-gap:20px;}.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);}.kb-portfolio-loop3947_e27353-53 .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}.kb-portfolio-loop3947_e27353-53 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kb-portfolio-loop3947_e27353-53{margin-bottom:20px;}}<\/style><div class=\" wp-block-kadence-portfoliogrid kb-blocks-portfolio-loop-block alignnone kb-portfolio-loop3947_e27353-53 kb-portfolio-grid-layout-grid \"><div class=\" kb-portfolio-grid-layout-grid-wrap kb-portfolio-grid-wrap kb-blocks-portfolio-img-hover-zoomout kb-blocks-portfolio-content-hover-zoomin\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"data-item-selector=\".kb-portfolio-masonry-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.666666666667%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Patras-Logo.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Patras-Logo.png 600w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Patras-Logo-300x200.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/university-of-patras-upatras\/\" aria-label=\"University of Patras (UPATRAS)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">University of Patras (UPATRAS)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Lead partner<\/div><\/div><\/div><\/div><\/div><div class=\"clearfix\" style=\"clear:both\"><\/div><\/div><\/div>\n\n<style>.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-grid-wrap{column-gap:60px;}.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-grid-wrap{row-gap:60px;}.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item{background-color:var(--global-palette8, #F7FAFC);border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-overlay-color{background-color:rgba(23, 104, 234, 0);}.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-color{background-color:rgba(158, 207, 229, 0.9);}.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item .entry-title{color:var(--global-palette3, #1A202C);padding:5px 0px 10px 0px;margin:0px 0px 0px 0px;font-size:19px;line-height:1.25;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:600;}.kb-portfolio-loop3947_54a82d-d6 .kb-filter-item{border-width:0px 0px 2px 0px;padding:5px 8px 5px 8px;margin:0px 10px 0px 0px;}@media all and (max-width: 1024px){.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 1024px){.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 1024px){.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-grid-wrap{column-gap:20px;row-gap:20px;}.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);}.kb-portfolio-loop3947_54a82d-d6 .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}.kb-portfolio-loop3947_54a82d-d6 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}}<\/style><div class=\" wp-block-kadence-portfoliogrid kb-blocks-portfolio-loop-block alignnone kb-portfolio-loop3947_54a82d-d6 kb-portfolio-grid-layout-grid \"><div class=\" kb-portfolio-grid-layout-grid-wrap kb-portfolio-grid-wrap kb-blocks-portfolio-img-hover-zoomout kb-blocks-portfolio-content-hover-zoomin\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"data-item-selector=\".kb-portfolio-masonry-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Peloponnese-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Peloponnese-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Peloponnese-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Peloponnese-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/University-of-Peloponnese.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/university-of-peloponnese-uop\/\" aria-label=\"University of Peloponnese (UOP)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">University of Peloponnese (UOP)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Haaga-Helia-University-of-Applied-Sciences-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Haaga-Helia-University-of-Applied-Sciences-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Haaga-Helia-University-of-Applied-Sciences-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Haaga-Helia-University-of-Applied-Sciences-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Haaga-Helia-University-of-Applied-Sciences.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/haaga-helia-university-of-applied-sciences-hhuas\/\" aria-label=\"Haaga-Helia University of Applied Sciences (HHUAS)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Haaga-Helia University of Applied Sciences (HHUAS)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Kaunas-University-of-Technology-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Kaunas-University-of-Technology-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Kaunas-University-of-Technology-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Kaunas-University-of-Technology-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Kaunas-University-of-Technology.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/kaunas-university-of-technology-ktu\/\" aria-label=\"Kaunas University of Technology (KTU)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Kaunas University of Technology (KTU)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Code.Hub-1-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Code.Hub-1-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Code.Hub-1-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Code.Hub-1-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Code.Hub-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/codehub-codehub\/\" aria-label=\"Codehub (CODEHUB)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Codehub (CODEHUB)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Olympic-Training-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Olympic-Training-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Olympic-Training-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Olympic-Training-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Olympic-Training.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/olympic-training-and-consulting-otc\/\" aria-label=\"Olympic Training and Consulting (OTC)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Olympic Training and Consulting (OTC)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Politeknika-Ikastegia-Txorierri-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Politeknika-Ikastegia-Txorierri-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Politeknika-Ikastegia-Txorierri-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Politeknika-Ikastegia-Txorierri-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Politeknika-Ikastegia-Txorierri.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/politeknika-txorierri-txorierri\/\" aria-label=\"Politeknika Txorierri (TXORIERRI)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Politeknika Txorierri (TXORIERRI)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-DIGITAL-SME-Alliance-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-DIGITAL-SME-Alliance-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-DIGITAL-SME-Alliance-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-DIGITAL-SME-Alliance-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-DIGITAL-SME-Alliance.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/european-digital-sme-alliance-digital-sme\/\" aria-label=\"European DIGITAL SME Alliance (DIGITAL SME)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">European DIGITAL SME Alliance (DIGITAL SME)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.666666666667%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/GAIA-Asociacion-de-Industrias-de-Conocimiento-y-Tecnologia-Logo.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/GAIA-Asociacion-de-Industrias-de-Conocimiento-y-Tecnologia-Logo.png 600w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/GAIA-Asociacion-de-Industrias-de-Conocimiento-y-Tecnologia-Logo-300x200.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/association-of-applied-knowledge-and-technology-industries-gaia\/\" aria-label=\"Association of Applied Knowledge and Technology Industries (GAIA)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Association of Applied Knowledge and Technology Industries (GAIA)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Ruse-Chamber-of-Commerce-and-Industry-RCCI-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Ruse-Chamber-of-Commerce-and-Industry-RCCI-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Ruse-Chamber-of-Commerce-and-Industry-RCCI-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Ruse-Chamber-of-Commerce-and-Industry-RCCI-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Ruse-Chamber-of-Commerce-and-Industry-RCCI.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/ruse-chamber-of-commerce-and-industry-rcci\/\" aria-label=\"Ruse Chamber of Commerce and Industry (RCCI)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Ruse Chamber of Commerce and Industry (RCCI)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/abodoo-logo-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/abodoo-logo-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/abodoo-logo-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/abodoo-logo-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/abodoo-logo.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/abodoo-abodoo\/\" aria-label=\"Abodoo (ABODOO)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Abodoo (ABODOO)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Royal-Melbourne-Institute-of-Technology-RMIT-Spain-logo-1-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Royal-Melbourne-Institute-of-Technology-RMIT-Spain-logo-1-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Royal-Melbourne-Institute-of-Technology-RMIT-Spain-logo-1-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Royal-Melbourne-Institute-of-Technology-RMIT-Spain-logo-1-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Royal-Melbourne-Institute-of-Technology-RMIT-Spain-logo-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/royal-melbourne-institute-of-technology-europe-rmit-europe\/\" aria-label=\"Royal Melbourne Institute of Technology Europe (RMIT Europe)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Royal Melbourne Institute of Technology Europe (RMIT Europe)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-Software-Institute-ESI-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"European Software Institute (ESI)\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-Software-Institute-ESI-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-Software-Institute-ESI-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-Software-Institute-ESI-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-Software-Institute-ESI-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/European-Software-Institute-ESI.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/european-software-institute-esi\/\" aria-label=\"European Software Institute (ESI)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">European Software Institute (ESI)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Project partner<\/div><\/div><\/div><\/div><\/div><div class=\"clearfix\" style=\"clear:both\"><\/div><\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3947_34fd12-66, .wp-block-kadence-advancedheading.kt-adv-heading3947_34fd12-66[data-kb-block=\"kb-adv-heading3947_34fd12-66\"]{max-width:650px;font-weight:500;font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3947_34fd12-66 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3947_34fd12-66[data-kb-block=\"kb-adv-heading3947_34fd12-66\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3947_34fd12-66 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3947_34fd12-66[data-kb-block=\"kb-adv-heading3947_34fd12-66\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading3947_34fd12-66 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3947_34fd12-66\">Associated Partners<\/h3>\n\n\n<style>.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-grid-wrap{column-gap:60px;}.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-grid-wrap{row-gap:60px;}.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item{background-color:var(--global-palette8, #F7FAFC);border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-overlay-color{background-color:rgba(23, 104, 234, 0);}.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-color{background-color:rgba(158, 207, 229, 0.9);}.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item .entry-title{color:var(--global-palette3, #1A202C);padding:5px 0px 10px 0px;margin:0px 0px 0px 0px;font-size:19px;line-height:1.25;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:600;}.kb-portfolio-loop3947_85dd0e-2a .kb-filter-item{border-width:0px 0px 2px 0px;padding:5px 8px 5px 8px;margin:0px 10px 0px 0px;}@media all and (max-width: 1024px){.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 1024px){.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 1024px){.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-grid-wrap{column-gap:20px;row-gap:20px;}.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:1px solid var(--global-palette6, #718096);}.kb-portfolio-loop3947_85dd0e-2a .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette8, #F7FAFC);border-right:1px solid var(--global-palette8, #F7FAFC);border-bottom:1px solid var(--global-palette8, #F7FAFC);border-left:1px solid var(--global-palette8, #F7FAFC);}.kb-portfolio-loop3947_85dd0e-2a .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}}<\/style><div class=\" wp-block-kadence-portfoliogrid kb-blocks-portfolio-loop-block alignnone kb-portfolio-loop3947_85dd0e-2a kb-portfolio-grid-layout-grid \"><div class=\" kb-portfolio-grid-layout-grid-wrap kb-portfolio-grid-wrap kb-blocks-portfolio-img-hover-zoomout kb-blocks-portfolio-content-hover-zoomin\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"data-item-selector=\".kb-portfolio-masonry-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/TKNIKA-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/TKNIKA-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/TKNIKA-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/TKNIKA-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/TKNIKA-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/TKNIKA.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/basque-centre-of-research-and-applied-innovation-in-vet-tknika\/\" aria-label=\"Basque Centre of Research and Applied Innovation in VET (TKNIKA)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Basque Centre of Research and Applied Innovation in VET (TKNIKA)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/HETEL-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/HETEL-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/HETEL-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/HETEL-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/HETEL-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/HETEL.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/association-of-vet-schools-in-the-basque-country-hetel\/\" aria-label=\"Association of VET Schools in the Basque Country (HETEL)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Association of VET Schools in the Basque Country (HETEL)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Development-Agency-of-the-Municipality-of-Trikala-e-Trikala-S.A-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Development Agency of the Municipality of Trikala (e-Trikala S.A.)\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Development-Agency-of-the-Municipality-of-Trikala-e-Trikala-S.A-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Development-Agency-of-the-Municipality-of-Trikala-e-Trikala-S.A-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Development-Agency-of-the-Municipality-of-Trikala-e-Trikala-S.A-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Development-Agency-of-the-Municipality-of-Trikala-e-Trikala-S.A-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Development-Agency-of-the-Municipality-of-Trikala-e-Trikala-S.A.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/development-agency-of-the-municipality-of-trikala-e-trikala-s-a\/\" aria-label=\"Development Agency of the Municipality of Trikala (e-Trikala S.A.)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Development Agency of the Municipality of Trikala (e-Trikala S.A.)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Athens-Tech-College-ATHTECH-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Athens Tech College (ATH\/TECH)\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Athens-Tech-College-ATHTECH-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Athens-Tech-College-ATHTECH-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Athens-Tech-College-ATHTECH-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Athens-Tech-College-ATHTECH-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Athens-Tech-College-ATHTECH.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/athens-tech-college-ath-tech\/\" aria-label=\"Athens Tech College (ATH\/TECH)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Athens Tech College (ATH\/TECH)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Headai-HeadAI-Ltd-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Headai (HeadAI Ltd)\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Headai-HeadAI-Ltd-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Headai-HeadAI-Ltd-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Headai-HeadAI-Ltd-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Headai-HeadAI-Ltd-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Headai-HeadAI-Ltd.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/headai-headai-ltd\/\" aria-label=\"Headai (HeadAI Ltd)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Headai (HeadAI Ltd)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/University-of-Ruse-Angel-Kanchev-UR-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"University of Ruse \u201cAngel Kanchev\u201d (UR)\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/University-of-Ruse-Angel-Kanchev-UR-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/University-of-Ruse-Angel-Kanchev-UR-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/University-of-Ruse-Angel-Kanchev-UR-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/University-of-Ruse-Angel-Kanchev-UR-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/University-of-Ruse-Angel-Kanchev-UR.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/university-of-ruse-angel-kanchev-ur\/\" aria-label=\"University of Ruse \u201cAngel Kanchev\u201d (UR)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">University of Ruse \u201cAngel Kanchev\u201d (UR)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:66.69921875%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Royal-Melbourne-Institute-of-Technology-RMIT-University-1024x683.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Royal Melbourne Institute of Technology (RMIT University)\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Royal-Melbourne-Institute-of-Technology-RMIT-University-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Royal-Melbourne-Institute-of-Technology-RMIT-University-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Royal-Melbourne-Institute-of-Technology-RMIT-University-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Royal-Melbourne-Institute-of-Technology-RMIT-University-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/11\/Royal-Melbourne-Institute-of-Technology-RMIT-University.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/partner\/royal-melbourne-institute-of-technology-rmit-university\/\" aria-label=\"Royal Melbourne Institute of Technology (RMIT University)\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Royal Melbourne Institute of Technology (RMIT University)<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Associated partner<\/div><\/div><\/div><\/div><\/div><div class=\"clearfix\" style=\"clear:both\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3094_90c478-4f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_90c478-4f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_90c478-4f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_90c478-4f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_90c478-4f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_90c478-4f > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_90c478-4f alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3094_d7b550-8f > .kt-inside-inner-col,.kadence-column3094_d7b550-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_d7b550-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_d7b550-8f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_d7b550-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_d7b550-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_d7b550-8f{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_d7b550-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_d7b550-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_d7b550-8f\" data-aos=\"fade-up\" data-aos-duration=\"600\" data-aos-once=\"true\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3094_86b21a-de > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3094_86b21a-de > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3094_86b21a-de > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3094_86b21a-de > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_86b21a-de > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3094_86b21a-de > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_86b21a-de alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column3094_09e39d-4c > .kt-inside-inner-col{display:flex;}.kadence-column3094_09e39d-4c > .kt-inside-inner-col,.kadence-column3094_09e39d-4c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_09e39d-4c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_09e39d-4c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_09e39d-4c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3094_09e39d-4c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_09e39d-4c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_09e39d-4c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_09e39d-4c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_09e39d-4c{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3094_09e39d-4c{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_09e39d-4c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_09e39d-4c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column3094_09e39d-4c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3094_09e39d-4c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_09e39d-4c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_09e39d-4c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_09e39d-4c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_09e39d-4c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a, .wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a[data-kb-block=\"kb-adv-heading3094_57b220-3a\"]{padding-top:0px;margin-top:0px;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.4;font-weight:500;font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a[data-kb-block=\"kb-adv-heading3094_57b220-3a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a[data-kb-block=\"kb-adv-heading3094_57b220-3a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a, .wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a[data-kb-block=\"kb-adv-heading3094_57b220-3a\"]{padding-right:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a, .wp-block-kadence-advancedheading.kt-adv-heading3094_57b220-3a[data-kb-block=\"kb-adv-heading3094_57b220-3a\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h3 class=\"kt-adv-heading3094_57b220-3a wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3094_57b220-3a\">Mission and Vision: Empowering the Future through AI Education<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{display:flex;}.kadence-column3094_71f1fc-01 > .kt-inside-inner-col,.kadence-column3094_71f1fc-01 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_71f1fc-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3094_71f1fc-01{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_71f1fc-01{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_71f1fc-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_71f1fc-01{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3094_71f1fc-01{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_71f1fc-01{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3094_71f1fc-01{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_71f1fc-01{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_71f1fc-01 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_71f1fc-01\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa, .wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa[data-kb-block=\"kb-adv-heading3094_ffbd6f-aa\"]{padding-top:0px;margin-top:0px;font-weight:300;font-style:normal;font-family:var( u002du002dglobal-body-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa[data-kb-block=\"kb-adv-heading3094_ffbd6f-aa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa[data-kb-block=\"kb-adv-heading3094_ffbd6f-aa\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa, .wp-block-kadence-advancedheading.kt-adv-heading3094_ffbd6f-aa[data-kb-block=\"kb-adv-heading3094_ffbd6f-aa\"]{padding-left:0px;}}<\/style>\n<p class=\"kt-adv-heading3094_ffbd6f-aa wp-block-kadence-advancedheading has-theme-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading3094_ffbd6f-aa\">The GenAISA consortium is united by a shared mission: to bridge the skills gap in generative AI and equip learners with the knowledge and resilience needed to thrive in a rapidly evolving world. Our vision is to create a transformative educational framework that fosters innovation, inclusivity, and ethical use of AI technologies, shaping a brighter, more connected future for all.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap .kt-video-svg-icon{color:var(--global-palette1, #3182CE);}.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap .kt-video-svg-icon > svg{stroke-width:2;}.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap:hover .kt-video-svg-icon{color:var(--global-palette2, #2B6CB0);}.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap .kadence-video-overlay{opacity:0;;mix-blend-mode:none;;background:#000000;;}.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap:hover .kadence-video-overlay{opacity:0;;}.glightbox-kadence-dark.kadence-popup-3094_c77e0d-bf .goverlay{background:#000000;opacity:0.8;}.glightbox-container.kadence-popup-3094_c77e0d-bf .gclose path, .glightbox-container.kadence-popup-3094_c77e0d-bf .gnext path, .glightbox-container.kadence-popup-3094_c77e0d-bf .gprev path{fill:#ffffff;}.glightbox-container.kadence-popup-3094_c77e0d-bf .gslide-video, .glightbox-container.kadence-popup-3094_c77e0d-bf .gvideo-local{max-width:80vw !important;}@media all and (max-width: 1024px){.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.kadence-video-popup3094_c77e0d-bf .kadence-video-popup-wrap{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);}.kadence-video-popup3094_c77e0d-bf{padding-right:0px;padding-left:0px;}.glightbox-container.kadence-popup-3094_c77e0d-bf .gslide-video, .glightbox-container.kadence-popup-3094_c77e0d-bf .gvideo-local{max-width:80vw;}}<\/style>\n<div class=\"wp-block-kadence-videopopup kadence-video-popup3094_c77e0d-bf\"><div class=\"kadence-video-popup-wrap kadence-video-noshadow\"><div class=\"kadence-video-intrinsic  kadence-video-set-ratio-56.25\" style=\"padding-bottom:56.25%\"><video src=\"https:\/\/genaisa.s3.us-east-1.amazonaws.com\/GenAISA+%E2%80%94+Promo+Video.mp4\" autoplay loop muted playsinline class=\"kadence-video-poster\"><\/video><div class=\"kadence-video-overlay\"><\/div><a class=\"kadence-video-popup-link kadence-video-type-external\" href=\"https:\/\/genaisa.s3.us-east-1.amazonaws.com\/GenAISA+%E2%80%94+Promo+Video.mp4\" role=\"button\" data-popup-class=\"kadence-popup-3094_c77e0d-bf\" data-effect=\"fade\" data-popup-id=\"kadence-local-video-3094_c77e0d-bf\" data-popup-auto=\"true\" data-youtube-cookies=\"true\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_play kt-video-svg-icon kt-video-svg-icon-style-default kt-video-svg-icon-fas play kt-video-play-animation-none kt-video-svg-icon-size-auto\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Play<\/title><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"\/><\/svg><\/span><\/a><\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-id3094_1e4dbd-73 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_1e4dbd-73 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_1e4dbd-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3094_1e4dbd-73 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_1e4dbd-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3094_1e4dbd-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_1e4dbd-73 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3094_6187c1-50 > .kt-inside-inner-col,.kadence-column3094_6187c1-50 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_6187c1-50 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_6187c1-50 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_6187c1-50 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_6187c1-50 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_6187c1-50{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_6187c1-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_6187c1-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_6187c1-50\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d, .wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d[data-kb-block=\"kb-adv-heading3094_2d750e-1d\"]{padding-top:0px;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.4;font-weight:500;font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d[data-kb-block=\"kb-adv-heading3094_2d750e-1d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d[data-kb-block=\"kb-adv-heading3094_2d750e-1d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d, .wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d[data-kb-block=\"kb-adv-heading3094_2d750e-1d\"]{padding-right:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d, .wp-block-kadence-advancedheading.kt-adv-heading3094_2d750e-1d[data-kb-block=\"kb-adv-heading3094_2d750e-1d\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h3 class=\"kt-adv-heading3094_2d750e-1d wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3094_2d750e-1d\">The Journey to Transforming AI Education<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c, .wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c[data-kb-block=\"kb-adv-heading3094_86a707-3c\"]{padding-top:0px;font-weight:300;font-style:normal;font-family:var( --global-body-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c[data-kb-block=\"kb-adv-heading3094_86a707-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c[data-kb-block=\"kb-adv-heading3094_86a707-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c, .wp-block-kadence-advancedheading.kt-adv-heading3094_86a707-3c[data-kb-block=\"kb-adv-heading3094_86a707-3c\"]{padding-left:0px;}}<\/style>\n<p class=\"kt-adv-heading3094_86a707-3c wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading3094_86a707-3c\">The GenAISA project sets ambitious goals to reshape education and training by creating specialized programs on generative AI. These expected outcomes highlight our dedication to equipping learners with advanced skills, promoting ethical AI use, and driving innovation across Europe.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{display:flex;}.kadence-column3094_ab6b51-64 > .kt-inside-inner-col,.kadence-column3094_ab6b51-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{flex-direction:column;justify-content:space-between;}.kadence-column3094_ab6b51-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3094_ab6b51-64{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_ab6b51-64{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{flex-direction:column;justify-content:space-between;}.kadence-column3094_ab6b51-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_ab6b51-64{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3094_ab6b51-64{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_ab6b51-64{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{flex-direction:column;justify-content:space-between;}}@media all and (max-width: 1024px){.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{flex-direction:column;justify-content:space-between;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3094_ab6b51-64{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_ab6b51-64{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{flex-direction:column;justify-content:space-between;}.kadence-column3094_ab6b51-64{text-align:center;}.kadence-column3094_ab6b51-64 > .kt-inside-inner-col{flex-direction:column;justify-content:space-between;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_ab6b51-64\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );padding-top:var(--global-kb-spacing-xxs, 0.5rem);}.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3094_13caa8-a1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3094_13caa8-a1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_13caa8-a1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-two-grid kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3094_243645-51 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3094_243645-51 > .kt-inside-inner-col{border-right:1px solid var(--global-palette6, #718096);}.kadence-column3094_243645-51 > .kt-inside-inner-col,.kadence-column3094_243645-51 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_243645-51 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_243645-51 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_243645-51 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_243645-51 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_243645-51{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_243645-51 > .kt-inside-inner-col{border-right:1px solid var(--global-palette6, #718096);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_243645-51 > .kt-inside-inner-col{border-top:0px solid transparent;border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:0px solid transparent;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_243645-51\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-3094_5cc5ff-38 .kb-count-up-title{color:var(--global-palette3, #1A202C);font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:400;}.kb-count-up-3094_5cc5ff-38 .kb-count-up-number{color:var(--global-palette2, #2B6CB0);font-size:var(--global-kb-font-size-xxl, 4rem);line-height:1.2;font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:500;}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-3094_5cc5ff-38 kb-count-up\" data-start=\"0\" data-end=\"3\" data-prefix=\"\" data-suffix=\"\" data-duration=\"2.5\" data-separator=\"\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">Years of Project Duration<\/p><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_15af52-86 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3094_15af52-86 > .kt-inside-inner-col,.kadence-column3094_15af52-86 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_15af52-86 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_15af52-86 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_15af52-86 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_15af52-86 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_15af52-86{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_15af52-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_15af52-86 > .kt-inside-inner-col{border-top:0px solid transparent;border-right:0px solid rgba(158,207,229,0);border-bottom:1px solid var(--global-palette6, #718096);border-left:0px solid transparent;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_15af52-86\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-3094_853e2b-97 .kb-count-up-title{color:var(--global-palette3, #1A202C);font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:400;}.kb-count-up-3094_853e2b-97 .kb-count-up-number{color:var(--global-palette2, #2B6CB0);font-size:var(--global-kb-font-size-xxl, 4rem);line-height:1.2;font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:500;}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-3094_853e2b-97 kb-count-up\" data-start=\"0\" data-end=\"200\" data-prefix=\"\" data-suffix=\"+\" data-duration=\"2.5\" data-separator=\"\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">Expected Pilot Participants<\/p><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_d0b357-ef > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3094_d0b357-ef > .kt-inside-inner-col{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);}.kadence-column3094_d0b357-ef > .kt-inside-inner-col,.kadence-column3094_d0b357-ef > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_d0b357-ef > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_d0b357-ef > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_d0b357-ef > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_d0b357-ef > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_d0b357-ef{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_d0b357-ef > .kt-inside-inner-col{border-top:1px solid var(--global-palette6, #718096);border-right:1px solid var(--global-palette6, #718096);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_d0b357-ef > .kt-inside-inner-col{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette6, #718096);border-left:0px solid transparent;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_d0b357-ef\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-3094_37f68f-ac .kb-count-up-title{color:var(--global-palette3, #1A202C);font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:400;}.kb-count-up-3094_37f68f-ac .kb-count-up-number{color:var(--global-palette2, #2B6CB0);font-size:var(--global-kb-font-size-xxl, 4rem);line-height:1.2;font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:500;}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-3094_37f68f-ac kb-count-up\" data-start=\"0\" data-end=\"10\" data-prefix=\"\" data-suffix=\"+\" data-duration=\"2.5\" data-separator=\"\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">Courses Expected for Higher and Vocational Education<\/p><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_d6d084-f0 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3094_d6d084-f0 > .kt-inside-inner-col{border-top:1px solid var(--global-palette6, #718096);}.kadence-column3094_d6d084-f0 > .kt-inside-inner-col,.kadence-column3094_d6d084-f0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_d6d084-f0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_d6d084-f0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_d6d084-f0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_d6d084-f0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_d6d084-f0{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_d6d084-f0 > .kt-inside-inner-col{border-top:1px solid var(--global-palette6, #718096);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_d6d084-f0 > .kt-inside-inner-col{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid rgba(158,207,229,0);border-bottom:0px solid transparent;border-left:0px solid transparent;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_d6d084-f0\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-3094_068b4d-43 .kb-count-up-title{color:var(--global-palette3, #1A202C);font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:400;}.kb-count-up-3094_068b4d-43 .kb-count-up-number{color:var(--global-palette2, #2B6CB0);font-size:var(--global-kb-font-size-xxl, 4rem);line-height:1.2;font-family:var( u002du002dglobal-heading-font-family, inherit );font-weight:500;}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-3094_068b4d-43 kb-count-up\" data-start=\"0\" data-end=\"100\" data-prefix=\"\" data-suffix=\"+\" data-duration=\"2.5\" data-separator=\"\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">Learning Resources Anticipated to Be Developed<\/p><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3094_08646c-16 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_08646c-16 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_08646c-16 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-lg, 4rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_08646c-16{background-image:linear-gradient(120deg,var(--global-palette3) 0%,var(--global-palette4) 100%);}.kb-row-layout-id3094_08646c-16 > .kt-row-layout-overlay{opacity:0.42;background-image:url('https:\/\/genaisa.eu\/wp-content\/uploads\/2024\/08\/gradient-2.webp');background-size:cover;background-position:center center;background-attachment:fixed;background-repeat:no-repeat;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id3094_08646c-16 > .kt-row-layout-overlay{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id3094_08646c-16 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_08646c-16 > .kt-row-column-wrap{padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_08646c-16 alignfull has-theme-palette4-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3094_583493-c0 > .kt-inside-inner-col,.kadence-column3094_583493-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_583493-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_583493-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_583493-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_583493-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_583493-c0{text-align:center;}.kadence-column3094_583493-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_583493-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_583493-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_583493-c0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_c0a62b-75, .wp-block-kadence-advancedheading.kt-adv-heading3094_c0a62b-75[data-kb-block=\"kb-adv-heading3094_c0a62b-75\"]{max-width:610px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3094_c0a62b-75 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_c0a62b-75[data-kb-block=\"kb-adv-heading3094_c0a62b-75\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_c0a62b-75 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_c0a62b-75[data-kb-block=\"kb-adv-heading3094_c0a62b-75\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3094_c0a62b-75 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3094_c0a62b-75\">Stay <mark class=\"kt-highlight\">Updated <\/mark>with the Latest in AI Insights<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3094_62c919-0e, .wp-block-kadence-advancedheading.kt-adv-heading3094_62c919-0e[data-kb-block=\"kb-adv-heading3094_62c919-0e\"]{max-width:700px;margin-right:auto;margin-left:auto;text-align:center;font-weight:300;font-style:normal;font-family:var( u002du002dglobal-body-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3094_62c919-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_62c919-0e[data-kb-block=\"kb-adv-heading3094_62c919-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_62c919-0e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_62c919-0e[data-kb-block=\"kb-adv-heading3094_62c919-0e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3094_62c919-0e wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3094_62c919-0e\">Dive into the latest updates, success stories, and training resources from the GenAISA project. Discover how we\u2019re advancing knowledge and skills in generative AI through innovative programs and collaborative efforts across Europe.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_62c52b-7f > .kt-inside-inner-col,.kadence-column3094_62c52b-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_62c52b-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_62c52b-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_62c52b-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_62c52b-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_62c52b-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_62c52b-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_62c52b-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_62c52b-7f\"><div class=\"kt-inside-inner-col\"><style>.kb-posts-id-3094_60d57e-ef .entry.loop-entry .entry-header .entry-title{font-size:31px;line-height:1.35;}.kb-posts-id-3094_60d57e-ef .kb-post-list-item{display:grid;}<\/style><ul class=\"wp-block-kadence-posts kb-posts kadence-posts-list kb-posts-id-3094_60d57e-ef content-wrap grid-cols kb-posts-style-boxed grid-sm-col-2 grid-lg-col-3 item-image-style-above\"><li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4335 post type-post status-publish format-standard has-post-thumbnail hentry category-generative-ai-insights\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/genaisa.eu\/el\/soft-skills-in-the-age-of-ai-why-communication-and-collaboration-matter-as-much-as-coding\/\" aria-label=\"Soft Skills in the Age of AI: Why Communication and Collaboration Matter as Much as Coding\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"429\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_danjs2danjs2danj-768x429.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Soft Skills in the Age of AI: Why Communication and Collaboration Matter as Much as Coding\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_danjs2danjs2danj-768x429.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_danjs2danjs2danj-300x167.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_danjs2danjs2danj-1024x572.png 1024w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-pill\">\n\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/category\/generative-ai-insights\/\" class=\"category-link-generative-ai-insights\" rel=\"tag\">Generative AI Insights<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><a href=\"https:\/\/genaisa.eu\/el\/soft-skills-in-the-age-of-ai-why-communication-and-collaboration-matter-as-much-as-coding\/\" rel=\"bookmark\">Soft Skills in the Age of AI: Why Communication and Collaboration Matter as Much as Coding<\/a><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"meta-label\">By<\/span><span class=\"author vcard\"><span class=\"fn n\">Nikolay Tsolev (RCCI)<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published\" datetime=\"2026-07-10T15:25:40+03:00\">10 \u0399\u03bf\u03c5\u03bb\u03af\u03bf\u03c5, 2026<\/time><time class=\"updated\" datetime=\"2026-07-10T15:28:23+03:00\">10 \u0399\u03bf\u03c5\u03bb\u03af\u03bf\u03c5, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n\t<div class=\"entry-summary\">\n\t\t<p>The rapid rise of generative artificial intelligence has fundamentally shifted the baseline of professional skills. Complex coding sequences can now be generated in seconds, data analysis can be automated with natural language prompts, and technical workflows that once required days of specialised labour are executed instantly. In this landscape, it is easy to assume that&#8230;<\/p>\n\t<\/div><!-- .entry-summary -->\n\t<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/soft-skills-in-the-age-of-ai-why-communication-and-collaboration-matter-as-much-as-coding\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> Soft Skills in the Age of AI: Why Communication and Collaboration Matter as Much as Coding<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4314 post type-post status-publish format-standard has-post-thumbnail hentry category-project-milestones\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/genaisa.eu\/el\/genaisa-partners-meet-in-kaunas-to-prepare-for-pilot-implementation\/\" aria-label=\"GenAISA Partners Meet in Kaunas to Prepare for Pilot Implementation\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"433\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326-768x433.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"GenAISA Partners Meet in Kaunas to Prepare for Pilot Implementation\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326-768x433.jpg 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326-300x169.jpg 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326-1024x577.jpg 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326-1536x865.jpg 1536w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326-18x10.jpg 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/07\/IMG_4326.jpg 1919w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-pill\">\n\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/category\/project-milestones\/\" class=\"category-link-project-milestones\" rel=\"tag\">Project Milestones<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><a href=\"https:\/\/genaisa.eu\/el\/genaisa-partners-meet-in-kaunas-to-prepare-for-pilot-implementation\/\" rel=\"bookmark\">GenAISA Partners Meet in Kaunas to Prepare for Pilot Implementation<\/a><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"meta-label\">By<\/span><span class=\"author vcard\"><span class=\"fn n\">Nikolay Tsolev (RCCI)<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published updated\" datetime=\"2026-07-02T14:01:59+03:00\">2 \u0399\u03bf\u03c5\u03bb\u03af\u03bf\u03c5, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n\t<div class=\"entry-summary\">\n\t\t<p>On 16\u201317 June 2026, the GenAISA consortium gathered in Kaunas, Lithuania, for the project&#8217;s fourth transnational meeting, hosted by Kaunas University of Technology (KTU). Representatives from the project partners came together to review the progress achieved across the project&#8217;s work packages and to coordinate the final preparations before the large-scale pilot implementation of the GenAISA&#8230;<\/p>\n\t<\/div><!-- .entry-summary -->\n\t<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/genaisa-partners-meet-in-kaunas-to-prepare-for-pilot-implementation\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> GenAISA Partners Meet in Kaunas to Prepare for Pilot Implementation<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4310 post type-post status-publish format-standard has-post-thumbnail hentry category-workshops-pilots\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/genaisa.eu\/el\/genaisa-workshop-offers-a-practical-look-at-the-potential-of-generative-artificial-intelligence\/\" aria-label=\"GenAISA workshop offers a practical look at the potential of generative artificial intelligence\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/image00067-1140x1520-1-768x1024.jpeg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"GenAISA workshop offers a practical look at the potential of generative artificial intelligence\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/image00067-1140x1520-1-768x1024.jpeg 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/image00067-1140x1520-1-225x300.jpeg 225w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/image00067-1140x1520-1-9x12.jpeg 9w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/image00067-1140x1520-1.jpeg 1140w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-pill\">\n\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/category\/workshops-pilots\/\" class=\"category-link-workshops-pilots\" rel=\"tag\">Workshops &amp; Pilots<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><a href=\"https:\/\/genaisa.eu\/el\/genaisa-workshop-offers-a-practical-look-at-the-potential-of-generative-artificial-intelligence\/\" rel=\"bookmark\">GenAISA workshop offers a practical look at the potential of generative artificial intelligence<\/a><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"meta-label\">By<\/span><span class=\"author vcard\"><span class=\"fn n\">Nikolay Tsolev (RCCI)<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published updated\" datetime=\"2026-06-12T15:58:21+03:00\">12 \u0399\u03bf\u03c5\u03bd\u03af\u03bf\u03c5, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n\t<div class=\"entry-summary\">\n\t\t<p>Generative artificial intelligence is rapidly transforming learning, work and creative processes. As a result, it is becoming increasingly important not only to observe the latest technological trends, but also to test new solutions in practice. This was the aim of the workshop organised as part of the Erasmus+ project GenAISA (Generative AI Skills Academy), during&#8230;<\/p>\n\t<\/div><!-- .entry-summary -->\n\t<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/genaisa-workshop-offers-a-practical-look-at-the-potential-of-generative-artificial-intelligence\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> GenAISA workshop offers a practical look at the potential of generative artificial intelligence<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4289 post type-post status-publish format-standard has-post-thumbnail hentry category-workshops-pilots\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/genaisa.eu\/el\/from-prompts-to-ai-agents-workshop-recap\/\" aria-label=\"From Prompts to\u00a0AI Agents &#8211; Workshop Recap\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-Jun-9-2026-01_35_23-PM-768x512.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"From Prompts to\u00a0AI Agents &#8211; Workshop Recap\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-Jun-9-2026-01_35_23-PM-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-Jun-9-2026-01_35_23-PM-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-Jun-9-2026-01_35_23-PM-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-Jun-9-2026-01_35_23-PM-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-Jun-9-2026-01_35_23-PM.png 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-pill\">\n\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/category\/workshops-pilots\/\" class=\"category-link-workshops-pilots\" rel=\"tag\">Workshops &amp; Pilots<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><a href=\"https:\/\/genaisa.eu\/el\/from-prompts-to-ai-agents-workshop-recap\/\" rel=\"bookmark\">From Prompts to\u00a0AI Agents &#8211; Workshop Recap<\/a><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"meta-label\">By<\/span><span class=\"author vcard\"><span class=\"fn n\">Nikolay Tsolev (RCCI)<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published\" datetime=\"2026-06-09T08:58:33+03:00\">9 \u0399\u03bf\u03c5\u03bd\u03af\u03bf\u03c5, 2026<\/time><time class=\"updated\" datetime=\"2026-06-10T09:19:53+03:00\">10 \u0399\u03bf\u03c5\u03bd\u03af\u03bf\u03c5, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n\t<div class=\"entry-summary\">\n\t\t<p>Workshop Recap \u2022 4 June 2026 From Promptsto AI Agents The workshop was jointly organised by GenAISA and Businessmap. Over 100 professionals joined us live to watch one sentence become a fully executable project plan, built in real time by a prompt that turns into an AI agent. 100+ Participants attended 31 Course registrations so&#8230;<\/p>\n\t<\/div><!-- .entry-summary -->\n\t<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/from-prompts-to-ai-agents-workshop-recap\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> From Prompts to\u00a0AI Agents &#8211; Workshop Recap<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4227 post type-post status-publish format-standard has-post-thumbnail hentry category-workshops-pilots\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/genaisa.eu\/el\/genaisa-workshop-in-greece-highlights-the-future-of-generative-ai-skills-and-education\/\" aria-label=\"GenAISA Workshop in Greece Highlights the Future of Generative AI Skills and Education\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"192\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/05\/1779989212323-768x192.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"GenAISA Workshop in Greece Highlights the Future of Generative AI Skills and Education\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/05\/1779989212323-768x192.jpg 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/05\/1779989212323-300x75.jpg 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/05\/1779989212323-1024x256.jpg 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/05\/1779989212323-18x5.jpg 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/05\/1779989212323.jpg 1280w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-pill\">\n\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/category\/workshops-pilots\/\" class=\"category-link-workshops-pilots\" rel=\"tag\">Workshops &amp; Pilots<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><a href=\"https:\/\/genaisa.eu\/el\/genaisa-workshop-in-greece-highlights-the-future-of-generative-ai-skills-and-education\/\" rel=\"bookmark\">GenAISA Workshop in Greece Highlights the Future of Generative AI Skills and Education<\/a><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"meta-label\">By<\/span><span class=\"author vcard\"><span class=\"fn n\">Nikolay Tsolev (RCCI)<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published updated\" datetime=\"2026-05-29T10:56:52+03:00\">29 \u039c\u03b1\u0390\u03bf\u03c5, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n\t<div class=\"entry-summary\">\n\t\t<p>The GenAISA project successfully delivered the workshop \u201cFrom Artificial Intelligence to the Skills of the Future\u201d in Patras, Greece, on May 20, 2026. The workshop that gathered almost 100 participants was co-organised by the University of Patras, the University of Peloponnese and Olympic Training and Consulting as a parallel session of the 14th Regional Growth&#8230;<\/p>\n\t<\/div><!-- .entry-summary -->\n\t<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/genaisa-workshop-in-greece-highlights-the-future-of-generative-ai-skills-and-education\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> GenAISA Workshop in Greece Highlights the Future of Generative AI Skills and Education<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4045 post type-post status-publish format-standard has-post-thumbnail hentry category-generative-ai-insights\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/genaisa.eu\/el\/genai-literacy-the-new-baseline-skill-every-business-must-build\/\" aria-label=\"GenAI Literacy: The new baseline skill every business must build\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-Apr-22-2026-10_02_01-AM-768x512.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"GenAI Literacy: The new baseline skill every business must build\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-Apr-22-2026-10_02_01-AM-768x512.png 768w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-Apr-22-2026-10_02_01-AM-300x200.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-Apr-22-2026-10_02_01-AM-1024x683.png 1024w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-Apr-22-2026-10_02_01-AM-18x12.png 18w, https:\/\/genaisa.eu\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-Apr-22-2026-10_02_01-AM.png 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-pill\">\n\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/category\/generative-ai-insights\/\" class=\"category-link-generative-ai-insights\" rel=\"tag\">Generative AI Insights<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><a href=\"https:\/\/genaisa.eu\/el\/genai-literacy-the-new-baseline-skill-every-business-must-build\/\" rel=\"bookmark\">GenAI Literacy: The new baseline skill every business must build<\/a><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"meta-label\">By<\/span><span class=\"author vcard\"><span class=\"fn n\">Nikolay Tsolev (RCCI)<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published\" datetime=\"2026-04-14T09:59:16+03:00\">14 \u0391\u03c0\u03c1\u03b9\u03bb\u03af\u03bf\u03c5, 2026<\/time><time class=\"updated\" datetime=\"2026-04-22T10:10:42+03:00\">22 \u0391\u03c0\u03c1\u03b9\u03bb\u03af\u03bf\u03c5, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n\t<div class=\"entry-summary\">\n\t\t<p>Companies across Europe are racing to deploy generative AI. Yet most are confusing access with readiness &#8211; and paying the price. Redesigning Work for the AI Era According to Deloitte&#8217;s State of AI in the Enterprise 2026, 84% of companies have not redesigned jobs or work processes around AI capabilities, despite recognising that insufficient worker&#8230;<\/p>\n\t<\/div><!-- .entry-summary -->\n\t<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/genaisa.eu\/el\/genai-literacy-the-new-baseline-skill-every-business-must-build\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> GenAI Literacy: The new baseline skill every business must build<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<\/ul>\n\n<style>.wp-block-kadence-advancedbtn.kt-btns3094_882119-dc, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns3094_882119-dc, .wp-block-kadence-advancedbtn.kb-btns3094_882119-dc, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns3094_882119-dc{margin-top:var(--global-kb-spacing-md, 2rem);}.wp-block-kadence-advancedbtn.kb-btns3094_882119-dc{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns3094_882119-dc .kt-button{font-weight:normal;font-style:normal;}.kt-btns3094_882119-dc .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3094_882119-dc .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3094_882119-dc .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3094_882119-dc .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3094_882119-dc .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3094_882119-dc .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3094_882119-dc .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3094_882119-dc\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3094_0b1f11-26.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3094_0b1f11-26.kb-button{background:var(--global-palette5, #4A5568);margin-top:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedbtn .kb-btn3094_0b1f11-26.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3094_0b1f11-26.kb-button:focus{background:var(--global-palette2, #2B6CB0);}<\/style><a class=\"kb-button kt-button button kb-btn3094_0b1f11-26 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/genaisa.eu\/news-events\/\"><span class=\"kt-btn-inner-text\">All News &amp; Events<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3094_d11cec-6a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_d11cec-6a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_d11cec-6a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:85px;padding-right:20px;padding-bottom:70px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_d11cec-6a > .kt-row-layout-overlay{opacity:0.33;mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id3094_d11cec-6a > .kt-row-column-wrap{padding-top:80px;padding-right:20px;padding-bottom:150px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3094_d11cec-6a > .kt-row-column-wrap{padding-top:60px;padding-right:20px;padding-bottom:60px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_d11cec-6a alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col,.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_d4cfb6-4a{position:relative;}.kadence-column3094_d4cfb6-4a, .kt-inside-inner-col > .kadence-column3094_d4cfb6-4a:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_d4cfb6-4a > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}.kadence-column3094_d4cfb6-4a, .kt-inside-inner-col > .kadence-column3094_d4cfb6-4a:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_d4cfb6-4a inner-column-1\" data-aos=\"fade-up\" data-aos-duration=\"600\" data-aos-once=\"true\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3094_c827bf-d2 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3094_c827bf-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3094_c827bf-d2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3094_c827bf-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_c827bf-d2 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3094_c827bf-d2{margin-bottom:var(--global-kb-spacing-lg, 3rem);}.kb-row-layout-id3094_c827bf-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_c827bf-d2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{display:flex;}.kadence-column3094_b78aa0-7d > .kt-inside-inner-col,.kadence-column3094_b78aa0-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_b78aa0-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3094_b78aa0-7d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_b78aa0-7d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_b78aa0-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_b78aa0-7d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3094_b78aa0-7d{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_b78aa0-7d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3094_b78aa0-7d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_b78aa0-7d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_b78aa0-7d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_b78aa0-7d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11, .wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11[data-kb-block=\"kb-adv-heading3094_3f24f7-11\"]{max-width:530px;padding-top:0px;padding-bottom:10px;margin-top:0px;margin-bottom:0px;text-align:left;line-height:1.2;font-weight:500;font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11[data-kb-block=\"kb-adv-heading3094_3f24f7-11\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11[data-kb-block=\"kb-adv-heading3094_3f24f7-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11, .wp-block-kadence-advancedheading.kt-adv-heading3094_3f24f7-11[data-kb-block=\"kb-adv-heading3094_3f24f7-11\"]{font-size:32px;text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading3094_3f24f7-11 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3094_3f24f7-11\">Meet the Dedicated Team Behind GenAISA<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_844945-cf > .kt-inside-inner-col{display:flex;}.kadence-column3094_844945-cf > .kt-inside-inner-col,.kadence-column3094_844945-cf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_844945-cf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_844945-cf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_844945-cf > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3094_844945-cf{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_844945-cf{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_844945-cf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_844945-cf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_844945-cf{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3094_844945-cf{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_844945-cf{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_844945-cf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column3094_844945-cf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3094_844945-cf{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_844945-cf{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3094_844945-cf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column3094_844945-cf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_844945-cf\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39, .wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39[data-kb-block=\"kb-adv-heading3094_d89fc5-39\"]{text-align:left;font-weight:300;font-style:normal;font-family:var( u002du002dglobal-body-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39[data-kb-block=\"kb-adv-heading3094_d89fc5-39\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39[data-kb-block=\"kb-adv-heading3094_d89fc5-39\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39, .wp-block-kadence-advancedheading.kt-adv-heading3094_d89fc5-39[data-kb-block=\"kb-adv-heading3094_d89fc5-39\"]{text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading3094_d89fc5-39 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3094_d89fc5-39\">Discover the experts driving the success of GenAISA. With diverse backgrounds in AI, education, research, and project management, our team combines innovation and expertise to shape the future of generative AI education and training across Europe.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3094_671131-54{margin-top:0px;}.kb-row-layout-id3094_671131-54 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_671131-54 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_671131-54 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:0px;padding-bottom:30px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3094_671131-54 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3094_671131-54 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3094_671131-54{margin-top:-30px;}.kb-row-layout-id3094_671131-54 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_671131-54 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col,.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_e3e4ca-89{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_e3e4ca-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_e3e4ca-89 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-portfolio-loop3094_982b5a-93 .kb-portfolio-grid-wrap{column-gap:30px;}.kb-portfolio-loop3094_982b5a-93 .kb-portfolio-grid-wrap{row-gap:30px;}.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item{background-color:var(--global-palette6, #718096);border-top:0px solid;border-right:0px solid;border-bottom:0px solid;border-left:0px solid;border-top-left-radius:200px;border-top-right-radius:200px;border-bottom-right-radius:200px;border-bottom-left-radius:200px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-portfolio-loop3094_982b5a-93 .kb-portfolio-overlay-color{background-color:rgba(23, 104, 234, 0);}.kb-portfolio-loop3094_982b5a-93 .kb-portfolio-overlay-border{border-top:0px solid rgba(0,0,0,0);border-right:0px solid rgba(0,0,0,0);border-bottom:0px solid rgba(0,0,0,0);border-left:0px solid rgba(0,0,0,0);}.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-color{background-color:rgba(197, 110, 177, 0.9);}.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid rgba(255, 255, 255, 0.8);border-right:1px solid rgba(255, 255, 255, 0.8);border-bottom:1px solid rgba(255, 255, 255, 0.8);border-left:1px solid rgba(255, 255, 255, 0.8);border-top-left-radius:200px;border-top-right-radius:200px;border-bottom-right-radius:200px;border-bottom-left-radius:200px;}.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item .entry-title{padding:5px 0px 10px 0px;margin:0px 0px 0px 0px;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:inherit;}.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item .kb-blocks-portfolio-taxonomies{font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:inherit;}.kb-portfolio-loop3094_982b5a-93 .kb-filter-item{border-width:0px 0px 2px 0px;padding:5px 8px 5px 8px;margin:0px 10px 0px 0px;}@media all and (max-width: 1024px){.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item{border-top:0px solid;border-right:0px solid;border-bottom:0px solid;border-left:0px solid;}}@media all and (max-width: 1024px){.kb-portfolio-loop3094_982b5a-93 .kb-portfolio-overlay-border{border-top:0px solid rgba(0,0,0,0);border-right:0px solid rgba(0,0,0,0);border-bottom:0px solid rgba(0,0,0,0);border-left:0px solid rgba(0,0,0,0);}}@media all and (max-width: 1024px){.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid rgba(255, 255, 255, 0.8);border-right:1px solid rgba(255, 255, 255, 0.8);border-bottom:1px solid rgba(255, 255, 255, 0.8);border-left:1px solid rgba(255, 255, 255, 0.8);}}@media all and (max-width: 767px){.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item{border-top:0px solid;border-right:0px solid;border-bottom:0px solid;border-left:0px solid;}.kb-portfolio-loop3094_982b5a-93 .kb-portfolio-overlay-border{border-top:0px solid rgba(0,0,0,0);border-right:0px solid rgba(0,0,0,0);border-bottom:0px solid rgba(0,0,0,0);border-left:0px solid rgba(0,0,0,0);}.kb-portfolio-loop3094_982b5a-93 .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid rgba(255, 255, 255, 0.8);border-right:1px solid rgba(255, 255, 255, 0.8);border-bottom:1px solid rgba(255, 255, 255, 0.8);border-left:1px solid rgba(255, 255, 255, 0.8);}}<\/style><div class=\" wp-block-kadence-portfoliogrid kb-blocks-portfolio-loop-block alignnone kb-portfolio-loop3094_982b5a-93 kb-portfolio-grid-layout-grid \"><div class=\" kb-portfolio-grid-layout-grid-wrap kb-portfolio-grid-wrap kb-blocks-portfolio-img-hover-blur kb-blocks-portfolio-content-hover-zoomin\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"data-item-selector=\".kb-portfolio-masonry-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-100\" style=\"padding-bottom:100%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Juhani-Heikkinen.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Juhani Heikkinen\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Juhani-Heikkinen.png 750w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Juhani-Heikkinen-300x300.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Juhani-Heikkinen-150x150.png 150w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/expert\/juhani-heikkinen\/\" aria-label=\"Juhani Heikkinen\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Juhani Heikkinen<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Haaga-Helia University of Applied Sciences (HHUAS)<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-100\" style=\"padding-bottom:100%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Maria-Rigou-1.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Maria Rigou\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Maria-Rigou-1.png 750w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Maria-Rigou-1-300x300.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Maria-Rigou-1-150x150.png 150w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/expert\/maria-rigou\/\" aria-label=\"Maria Rigou\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Maria Rigou<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">University of Patras (UPATRAS)<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-100\" style=\"padding-bottom:100%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Expert-Placeholder.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Expert Placeholder\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Expert-Placeholder.png 750w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Expert-Placeholder-300x300.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Expert-Placeholder-150x150.png 150w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/expert\/andrius-krisciunas\/\" aria-label=\"Andrius Krisciunas\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Andrius Krisciunas<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Kaunas University of Technology (KTU)<\/div><\/div><\/div><\/div><\/div><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-100\" style=\"padding-bottom:100%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Jokin-Goioaga.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Jokin Goioaga\" srcset=\"https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Jokin-Goioaga.png 750w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Jokin-Goioaga-300x300.png 300w, https:\/\/genaisa.eu\/wp-content\/uploads\/2025\/01\/Jokin-Goioaga-150x150.png 150w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/genaisa.eu\/el\/expert\/jokin-goioaga\/\" aria-label=\"Jokin Goioaga\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h4 class=\"entry-title kb-portfolio-loop-title\">Jokin Goioaga<\/h4><div class=\"kb-blocks-portfolio-taxonomies\">Politeknika Txorierri (TXORIERRI)<\/div><\/div><\/div><\/div><\/div><div class=\"clearfix\" style=\"clear:both\"><\/div><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3094_6e2dda-d0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3094_6e2dda-d0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3094_6e2dda-d0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3094_6e2dda-d0{background-image:url('https:\/\/genaisa.eu\/wp-content\/uploads\/2024\/10\/lines.png');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id3094_6e2dda-d0 > .kt-row-layout-overlay{opacity:0.66;background:radial-gradient(circle at center bottom,var(--global-palette2) 0%,var(--global-palette3) 72%);}@media all and (max-width: 1024px){.kb-row-layout-id3094_6e2dda-d0 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3094_6e2dda-d0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3094_6e2dda-d0 alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col,.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_ed8ae1-28{position:relative;}@media all and (max-width: 1024px){.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_ed8ae1-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_ed8ae1-28\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3094_98b540-f3, .wp-block-kadence-advancedheading.kt-adv-heading3094_98b540-f3[data-kb-block=\"kb-adv-heading3094_98b540-f3\"]{max-width:850px;text-align:left;font-weight:500;font-style:normal;font-family:var( u002du002dglobal-heading-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3094_98b540-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_98b540-f3[data-kb-block=\"kb-adv-heading3094_98b540-f3\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_98b540-f3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_98b540-f3[data-kb-block=\"kb-adv-heading3094_98b540-f3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3094_98b540-f3 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3094_98b540-f3\">Subscribe to the GenAISA Newsletter<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3094_06b1f4-cc, .wp-block-kadence-advancedheading.kt-adv-heading3094_06b1f4-cc[data-kb-block=\"kb-adv-heading3094_06b1f4-cc\"]{max-width:700px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3094_06b1f4-cc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3094_06b1f4-cc[data-kb-block=\"kb-adv-heading3094_06b1f4-cc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3094_06b1f4-cc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3094_06b1f4-cc[data-kb-block=\"kb-adv-heading3094_06b1f4-cc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3094_06b1f4-cc wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3094_06b1f4-cc\">Get periodic updates from the GenAISA project\u2014new learning resources, workshop invites, pilot results, and funding or collaboration opportunities. No spam, unsubscribe anytime.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3094_60603f-a7 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column3094_60603f-a7 > .kt-inside-inner-col{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);}.kadence-column3094_60603f-a7 > .kt-inside-inner-col,.kadence-column3094_60603f-a7 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column3094_60603f-a7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3094_60603f-a7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3094_60603f-a7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3094_60603f-a7 > .kt-inside-inner-col{background-image:linear-gradient(0deg,var(--global-palette3) 41%,var(--global-palette1) 100%);}.kadence-column3094_60603f-a7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3094_60603f-a7 a{color:var(--global-palette9, #ffffff);}.kadence-column3094_60603f-a7 a:hover{color:var(--global-palette2, #2B6CB0);}.kadence-column3094_60603f-a7{position:relative;}.kadence-column3094_60603f-a7, .kt-inside-inner-col > .kadence-column3094_60603f-a7:not(.specificity){margin-top:-140px;}@media all and (max-width: 1024px){.kadence-column3094_60603f-a7 > .kt-inside-inner-col{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3094_60603f-a7 > .kt-inside-inner-col{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);flex-direction:column;justify-content:center;}.kadence-column3094_60603f-a7, .kt-inside-inner-col > .kadence-column3094_60603f-a7:not(.specificity){margin-top:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3094_60603f-a7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form textarea{color:var(--global-palette9, #ffffff);border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid transparent;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.wp-block-kadence-advanced-form3872-cpt-id{color-scheme:dark;--kb-form-text-color:var(--global-palette9, #ffffff);--kb-form-background-color:rgba(0,0,0,0);--kb-form-border-width:0px;}.wp-block-kadence-advanced-form3872-cpt-id{--kb-form-placeholder-color:var(--global-palette6, #718096);}.wp-block-kadence-advanced-form3872-cpt-id input[type=text]:focus,.wp-block-kadence-advanced-form3872-cpt-id input[type=email]:focus,.wp-block-kadence-advanced-form3872-cpt-id input[type=tel]:focus,.wp-block-kadence-advanced-form3872-cpt-id input[type=date]:focus,.wp-block-kadence-advanced-form3872-cpt-id input[type=number]:focus,.wp-block-kadence-advanced-form3872-cpt-id input[type=time]:focus,.wp-block-kadence-advanced-form3872-cpt-id input[type=file]:focus,.wp-block-kadence-advanced-form3872-cpt-id select:focus,.wp-block-kadence-advanced-form3872-cpt-id textarea:focus{border-color:var(--global-palette7, #EDF2F7);}.wp-block-kadence-advanced-form3872-cpt-id .kb-adv-form-field .kb-adv-form-label{color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form textarea{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3872-cpt-id .kb-advanced-form textarea{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid transparent;}}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form3872-cpt-id kb-adv-form-label-style-normal kb-adv-form-input-size-standard kb-form-basic-style kb-form-is-dark .custom-link\"><form id=\"kb-adv-form-3872-cpt-id\" class=\"kb-advanced-form\" method=\"post\">\n<style>.kb-row-layout-id3872_88aff7-f8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3872_88aff7-f8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3872_88aff7-f8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3872_88aff7-f8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3872_88aff7-f8 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3872_88aff7-f8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3872_88aff7-f8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3872_e0ed11-7e > .kt-inside-inner-col,.kadence-column3872_e0ed11-7e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3872_e0ed11-7e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3872_e0ed11-7e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3872_e0ed11-7e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3872_e0ed11-7e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3872_e0ed11-7e{position:relative;}@media all and (max-width: 1024px){.kadence-column3872_e0ed11-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3872_e0ed11-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3872_e0ed11-7e\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field387267fe0b-e8 wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field387267fe0b-e8\">First Name<\/label><input name=\"field67fe0b-e8\" id=\"field387267fe0b-e8\" data-label=\"First Name\" autocomplete=\"given-name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"no\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col,.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3872_3a6a7f-0d{position:relative;}@media all and (max-width: 1024px){.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3872_3a6a7f-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3872_3a6a7f-0d\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3872c3a110-6d wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field3872c3a110-6d\">Last Name<\/label><input name=\"fieldc3a110-6d\" id=\"field3872c3a110-6d\" data-label=\"Last Name\" autocomplete=\"family-name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"no\" \/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3872b0cd91-b8 wp-block-kadence-advanced-form-email\"><label class=\"kb-adv-form-label\" for=\"field3872b0cd91-b8\">Email<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldb0cd91-b8\" id=\"field3872b0cd91-b8\" data-label=\"Email\" autocomplete=\"email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div>\n\n<div class=\"kb-adv-form-field kb-field38729017fc-a9 wp-block-kadence-advanced-form-accept\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb38729017fc-a9\" data-type=\"accept\" data-required=\"yes\"  data-kb-required-message=\"Please agree to the privacy policy\" ><div class=\"kb-radio-check-item\"><input name=\"field9017fc-a9\" id=\"field38729017fc-a9_0\" data-label=\"\" type=\"checkbox\" value=\"accept\" data-type=\"accept\" class=\"kb-field kb-accept-field kb-checkbox-field\" data-required=\"yes\" required aria-required=\"true\" data-kb-required-message=\"Please agree to the privacy policy\" \/><label for=\"field38729017fc-a9_0\">I agree to the <a href=\"https:\/\/genaisa.eu\/privacy-policy\/\" data-type=\"page\" data-id=\"3\" target=\"_blank\" rel=\"noreferrer noopener\">Privacy Policy<\/a> and consent to my personal data being processed in accordance with it.<span class=\"kb-adv-form-required\">*<\/span><\/label><\/div><\/fieldset><\/div>\n\n<style>ul.menu .kb-submit-field .kb-btnc6c4f4-8a.kb-button{width:initial;}.kb-submit-field.kb-fieldc6c4f4-8a{justify-content:flex-start;}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-fieldc6c4f4-8a wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btnc6c4f4-8a kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false\" type=\"submit\"><span class=\"kt-btn-inner-text\">Subscribe<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"3872\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"3872-cpt-id\"><\/form><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u039f\u03bc\u03ac\u03b4\u03b1 &amp; \u03a3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b5\u03c2 \u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c0\u03b1\u03b3\u03b3\u03b5\u03bb\u03bc\u03b1\u03c4\u03af\u03b5\u03c2 \u03ba\u03b1\u03b9 \u03c4\u03bf\u03c5\u03c2 \u03bf\u03c1\u03b3\u03b1\u03bd\u03b9\u03c3\u03bc\u03bf\u03cd\u03c2 \u03c0\u03bf\u03c5 \u03c0\u03c1\u03bf\u03c9\u03b8\u03bf\u03cd\u03bd \u03c4\u03bf \u03cc\u03c1\u03b1\u03bc\u03b1 \u03c4\u03b7\u03c2 GenAISA, \u03c3\u03c5\u03bd\u03b4\u03c5\u03ac\u03b6\u03bf\u03bd\u03c4\u03b1\u03c2 \u03c4\u03b7\u03bd \u03c4\u03b5\u03c7\u03bd\u03bf\u03b3\u03bd\u03c9\u03c3\u03af\u03b1 \u03ba\u03b1\u03b9 \u03c4\u03b7\u03bd \u03ba\u03b1\u03b9\u03bd\u03bf\u03c4\u03bf\u03bc\u03af\u03b1 \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u03c0\u03c1\u03bf\u03ce\u03b8\u03b7\u03c3\u03b7 \u03c4\u03b7\u03c2 \u03b5\u03ba\u03c0\u03b1\u03af\u03b4\u03b5\u03c5\u03c3\u03b7\u03c2 \u03c3\u03c4\u03b7\u03bd \u03c0\u03b1\u03c1\u03b1\u03b3\u03c9\u03b3\u03b9\u03ba\u03ae \u03a4\u03b5\u03c7\u03bd\u03b7\u03c4\u03ae \u039d\u03bf\u03b7\u03bc\u03bf\u03c3\u03cd\u03bd\u03b7. \u039f\u03b9 \u03a3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b5\u03c2 \u03bc\u03b1\u03c2: \u0388\u03bd\u03b1 \u0394\u03af\u03ba\u03c4\u03c5\u03bf \u0391\u03c1\u03b9\u03c3\u03c4\u03b5\u03af\u03b1\u03c2 \u0397 GenAISA \u03c5\u03c0\u03bf\u03c3\u03c4\u03b7\u03c1\u03af\u03b6\u03b5\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03bc\u03b9\u03b1 \u03c0\u03bf\u03b9\u03ba\u03b9\u03bb\u03cc\u03bc\u03bf\u03c1\u03c6\u03b7 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1 \u03c3\u03c5\u03bd\u03b5\u03c1\u03b3\u03b1\u03c4\u03ce\u03bd, \u03c3\u03c5\u03bc\u03c0\u03b5\u03c1\u03b9\u03bb\u03b1\u03bc\u03b2\u03b1\u03bd\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd \u03ba\u03bf\u03c1\u03c5\u03c6\u03b1\u03af\u03c9\u03bd \u03c0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03b7\u03bc\u03af\u03c9\u03bd, \u03ba\u03ad\u03bd\u03c4\u03c1\u03c9\u03bd \u03b5\u03c0\u03b1\u03b3\u03b3\u03b5\u03bb\u03bc\u03b1\u03c4\u03b9\u03ba\u03ae\u03c2 \u03ba\u03b1\u03c4\u03ac\u03c1\u03c4\u03b9\u03c3\u03b7\u03c2 \u03ba\u03b1\u03b9 \u03ba\u03b1\u03b9\u03bd\u03bf\u03c4\u03cc\u03bc\u03c9\u03bd \u03c4\u03bf\u03c5 \u03ba\u03bb\u03ac\u03b4\u03bf\u03c5 \u03b1\u03c0\u03cc \u03cc\u03bb\u03b7 \u03c4\u03b7\u03bd \u0395\u03c5\u03c1\u03ce\u03c0\u03b7. \u039a\u03ac\u03b8\u03b5 \u03c3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b7\u03c2 \u03c0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03b5\u03b9 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03ae \u03c4\u03b5\u03c7\u03bd\u03bf\u03b3\u03bd\u03c9\u03c3\u03af\u03b1 \u03ba\u03b1\u03b9...<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3094","page","type-page","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Svetoslav Minchev (RCCI)","author_link":"https:\/\/genaisa.eu\/el\/author\/admin_25h4lets\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/pages\/3094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/comments?post=3094"}],"version-history":[{"count":0,"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/pages\/3094\/revisions"}],"wp:attachment":[{"href":"https:\/\/genaisa.eu\/el\/wp-json\/wp\/v2\/media?parent=3094"}],"curies":[{"name":"\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}